{"id":19474,"date":"2025-04-29T12:40:41","date_gmt":"2025-04-29T12:40:41","guid":{"rendered":"https:\/\/www.saiebari.it\/?page_id=19474"},"modified":"2025-10-28T13:48:40","modified_gmt":"2025-10-28T13:48:40","slug":"piazza-cantiere-restauro","status":"publish","type":"page","link":"https:\/\/www.saiebari.it\/it\/piazza-cantiere-restauro\/","title":{"rendered":"Piazza Cantiere del Restauro"},"content":{"rendered":"[vc_row equal_height=&#8221;yes&#8221; el_class=&#8221;my-1&#8243;][vc_column width=&#8221;2\/3&#8243; el_class=&#8221;px-lg-5&#8243;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column_inner][vc_column_text]\n<h2>Tecnologie e strumenti per il restauro e la conservazione<\/h2>\n[\/vc_column_text][vc_column_text]Assorestauro ha organizzato nell\u2019ambito di SAIE Bari 2025 la <strong>Piazza Cantiere del Restauro<\/strong>, uno spazio dedicato ad attivit\u00e0 pratiche, workshop applicativi e panel tecnici per un evento a 360\u00b0 sul mondo della riqualificazione.<\/p>\n<p>Un\u2019occasione di incontro tra aziende, professionisti, istituzioni per guardare al futuro del settore e affrontare i principali temi di aggiornamento.[\/vc_column_text][vc_separator][vc_column_text]<em>\u201cContinua la collaborazione tra SAIE e Assorestauro per portare il mondo della riqualificazione architettonica e del restauro nella fiera delle costruzioni, un\u2019unione naturale e al passo con i tempi. <\/em><em>In italia infatti circa il 40% degli edifici \u00e8 stato realizzato prima del 1945, un patrimonio storico immenso che caratterizza i nostri centri urbani e luoghi culturali.<br \/>\nLa piazza<strong>\u00a0Cantiere del Restauro<\/strong>\u00a0all\u2019interno di SAIE, \u00e8 uno spazio espositivo e di dimostrazione pratica delle ultime tecnologie e materiali compatibili con gli edifici storici e con un approccio sostenibile.<br \/>\nUn cantiere aperto situato al centro della fiera, per scoprire insieme ai tecnici le applicazioni e le esperienze interattive che permette di vivere il restauro<\/em><em>\u201d<\/em><\/p>\n<p style=\"text-align: right\"><span style=\"color: #eb5b37\"><strong>Assorestauro<\/strong><\/span><\/p>\n[\/vc_column_text][vc_separator][vc_column_text]<a class=\"btn btn-lg my-0\" href=\"#programma\">Programma<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/3&#8243; el_class=&#8221;p-1 p-sm-3 p-lg-4 bg-darker&#8221;][vc_row_inner][vc_column_inner][vc_wp_custommenu nav_menu=&#8221;12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;my-1 bg-gray&#8221;][vc_column][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column_inner el_class=&#8221;col-img&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1717165638191{background-image: url(\/public\/uploads\/sites\/9\/IMG_Piazza_Restauro_2.jpg?id=23025) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][\/vc_column_inner][vc_column_inner el_class=&#8221;py-lg-2 px-lg-5&#8243; width=&#8221;2\/3&#8243;][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<h3>Perch\u00e9 visitare l&#8217;area ASSORESTAURO?<\/h3>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221;]<span style=\"font-size: 18px;line-height: 22px\"><span style=\"color: black\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-19071\" src=\"\/public\/uploads\/sites\/9\/SAIE-24_Punti-Elenco_1.png\" alt=\"\" width=\"30\" height=\"30\" \/><strong>Scoprire<\/strong> le novit\u00e0 di prodotto da introdurre in azienda<\/span><\/span>[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221;]<span style=\"font-size: 18px;line-height: 22px\"><span style=\"color: black\"><strong><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-19073\" src=\"\/public\/uploads\/sites\/9\/SAIE-24_Punti-Elenco_2.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/strong>Toccare con mano <strong>materiali<\/strong>, <strong>tecnologie<\/strong> e <strong>servizi utili<\/strong> per la tua professione<\/span><\/span>[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<p style=\"text-align: left\"><span style=\"font-size: 18px;line-height: 22px\"><span style=\"color: black\"><strong><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-19075\" src=\"\/public\/uploads\/sites\/9\/SAIE-24_Punti-Elenco_3.png\" alt=\"\" width=\"30\" height=\"30\" \/>Aggiornarsi<\/strong> sui temi tecnici di maggiore attualit\u00e0<\/span><\/span><\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<p style=\"text-align: left\"><span style=\"font-size: 18px;line-height: 22px\"><span style=\"color: black\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-19077\" src=\"\/public\/uploads\/sites\/9\/SAIE-24_Punti-Elenco_4.png\" alt=\"\" width=\"30\" height=\"30\" \/><strong>Trovare nuovi fornitori<\/strong><\/span><\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;my-1&#8243;][vc_column][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column_inner el_class=&#8221;py-lg-2 px-lg-5&#8243; width=&#8221;2\/3&#8243;][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<h3>Le iniziative della Piazza Cantiere del Restauro<\/h3>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221;]<span style=\"color: #eb5b37\"><strong>COLLETTIVA SOCI ASSORESTAURO<\/strong><\/span><\/p>\n<p>Area espositiva dedicata alle aziende associate di Assorestauro che rappresentano l\u2019intera filiera del restauro italiano, con produttori di materiali e tecnologie, laboratori di analisi e diagnostica sulle strutture, progettisti qualificati ed imprese certificate.[\/vc_column_text][vc_separator css_animation=&#8221;fadeIn&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221;]<span style=\"color: #eb5b37\"><strong>Piazza \u201cCantiere del Restauro\u201d<\/strong><\/span><\/p>\n<p>Uno spazio multifunzionale interamente dedicato alle aziende esportici con strumentazioni, macchinari e supporti tipici del cantiere di restauro, e uno spazio Talk per mostrare le ultime novit\u00e0 e progetti sul settore.<\/p>\n<p>Assorestauro \u00e8 l\u2019associazione che rappresenta il<strong>\u00a0mondo della conservazione e del restauro Made in Italy<\/strong>. \u00c8 la sintesi di diverse discipline, professionalit\u00e0 specializzate, tecnologie innovative e vocazioni imprenditoriali.[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;col-img&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1717165506120{background-image: url(\/public\/uploads\/sites\/9\/IMG_Piazza_Restauro_1.jpg?id=23023) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;py-lg-2 px-lg-5 bg-gray&#8221; el_id=&#8221;programma&#8221;][vc_column css=&#8221;.vc_custom_1564664077693{padding-top: 0px !important;}&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column_inner el_class=&#8221;py-lg-2 px-lg-5&#8243;][vc_column_text]\n<h3 style=\"text-align: center\"><strong>Programma Piazza Cantiere del Restauro 2025<\/strong><\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_text_separator title=&#8221;Gioved\u00ec 25 ottobre&#8221; title_align=&#8221;separator_align_left&#8221; align=&#8221;align_left&#8221; color=&#8221;custom&#8221; accent_color=&#8221;#f8b43f&#8221;][vc_column_text]\n<p style=\"text-align: left\">11:30 &#8211; 13:00<strong><br \/>\n<em>Innovazione e tradizione nel restauro<br \/>\n<\/em><\/strong>In collaborazione con <strong>Universit\u00e0 del SALENTO<\/strong>, <strong>SILTEA<\/strong>, <strong>OFFICINA ING. TARANTINO<\/strong><\/p>\n[\/vc_column_text][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#d6d6d6&#8243;][vc_column_text]\n<p style=\"text-align: left\">14:30 &#8211; 16:00<strong><br \/>\n<em>Tavola Rotonda: Efficientamento energetico degli edifici storici<br \/>\n<\/em><\/strong>In collaborazione con <strong>UNI<\/strong> e<strong> FEDERCOSTRUZIONI<\/strong>, <strong>Camera di Commercio di Brescia<\/strong>, <strong>DAIKIN<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;bg-gray&#8221; width=&#8221;1\/3&#8243;][vc_text_separator title=&#8221;Venerd\u00ec 24 ottobre&#8221; title_align=&#8221;separator_align_left&#8221; align=&#8221;align_left&#8221; color=&#8221;custom&#8221; accent_color=&#8221;#f8b43f&#8221;][vc_column_text]\n<p style=\"text-align: left\">10:00 &#8211; 11:30<strong><br \/>\n<em>Ricostruzione &#8211; strutture: materiali e progetto per la ricostruzione e prevenzione sismica<br \/>\n<\/em><\/strong>In collaborazione con <strong>ISI<\/strong>,<strong> FIBRENET<\/strong>,<strong> FASSA<\/strong><\/p>\n[\/vc_column_text][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#d6d6d6&#8243;][vc_column_text]\n<p style=\"text-align: left\">14:00 &#8211; 15:00<strong><br \/>\n<em>Digitalizzazione e BIM per i beni culturali: Il caso sperimentale della basilica di San Pietro a Roma<br \/>\n<\/em><\/strong>In collaborazione con <strong>Accasoftware<\/strong>, <strong>Basilica<\/strong> <strong>e Fabbrica di San Pietro<\/strong><\/p>\n[\/vc_column_text][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#d6d6d6&#8243;][vc_column_text]\n<p style=\"text-align: left\">15:30 &#8211; 16:00<br \/>\n<strong><em>Consolidare le murature con sistemi agili e compatibili<br \/>\n<\/em><\/strong>In collaborazione con <strong>KIMIA<em><br \/>\n<\/em><\/strong><\/p>\n[\/vc_column_text][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#d6d6d6&#8243;][vc_column_text]\n<p style=\"text-align: left\">16:00 &#8211; 18:00<strong><br \/>\n<em>Il restauro come connessione: luoghi, memorie, comunit\u00e0<\/em><\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;my-&#8221; width=&#8221;1\/3&#8243;][vc_text_separator title=&#8221;Sabato 25 ottobre&#8221; title_align=&#8221;separator_align_left&#8221; align=&#8221;align_left&#8221; color=&#8221;custom&#8221; accent_color=&#8221;#f8b43f&#8221;][vc_column_text]\n<p style=\"text-align: left\">11:30 &#8211; 13:00<strong><br \/>\n<em>Tavola Rotonda: La formazione per la gestione e manutenzione dei beni culturali<br \/>\n<\/em><\/strong>In collaborazione con <strong>ITS CAMPANIA<\/strong>,<strong> ACEN CAMPANIA<\/strong>,<strong> FORMEDIL &#8211; Roberta Vitale<\/strong><\/p>\n[\/vc_column_text][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#d6d6d6&#8243;][vc_column_text]\n<p style=\"text-align: left\">14:30 &#8211; 16:00<strong><br \/>\n<em>ANALISI E CONOSCENZA PER I BENI STORICI<br \/>\n<\/em><\/strong>In collaborazione con <strong>INDEP &#8211; Istituto Nazionale per la Diagnostica e Patologia Edilizia<\/strong>, <strong>CODIS<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]\n<p style=\"text-align: center\"><a class=\"btn btn-lg my-0\" href=\"https:\/\/espositori.saiebari.it\/portale\/it\/convegni\" target=\"_blank\" rel=\"noopener\">Programma Completo SAIE Bari 2025 \u00bb<\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;my-1&#8243;][vc_column][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; el_class=&#8221;py-lg-2 px-lg-5&#8243;][vc_column_inner el_class=&#8221;py-lg-2 px-lg-5&#8243;][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<h3 style=\"text-align: center\">La Piazza Cantiere del Restauro a SAIE 2024<\/h3>\n[\/vc_column_text][vc_media_grid grid_id=&#8221;vc_gid:1761659311208-b67ff097-4e51-1&#8243; include=&#8221;19683,19675,19681,19677,19679,19673&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column el_class=&#8221;px-lg-5&#8243;][vc_empty_space height=&#8221;50px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]\n<p style=\"text-align: center\"><em>Organizzato da<\/em><\/p>\n[\/vc_column_text][vc_separator][vc_single_image image=&#8221;19475&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;64px&#8221;][vc_column_text]\n<h3 style=\"text-align: center\"><b>Le aziende che hanno partecipato alla Piazza Cantiere del Restauro di SAIE Bari 2025<\/b><\/h3>\n[\/vc_column_text][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;22320&#8243; img_size=&#8221;250x&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;21862&#8243; primary_title=&#8221;&#8221; hover_title=&#8221;&#8221; hover_background_color=&#8221;custom&#8221; hover_btn_title=&#8221;<b>Leggi l&#8217;intervista<\/b>&#8221; hover_btn_style=&#8221;outline&#8221; hover_btn_color=&#8221;white&#8221; hover_btn_align=&#8221;center&#8221; hover_add_button=&#8221;true&#8221; hover_btn_link=&#8221;url:https%3A%2F%2Fwww.saiebari.it%2Fit%2Finterviste-espositori-2025%2Fmapei%2F&#8221; hover_custom_background=&#8221;#f7b71f&#8221;][\/vc_hoverbox][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;22325&#8243; img_size=&#8221;250x&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;22330&#8243; img_size=&#8221;250x&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column el_class=&#8221;my-1 bg-gray&#8221;][vc_row_inner][vc_column_inner][vc_empty_space][vc_column_text]\n<h3 style=\"text-align: center\">Scopri la lista delle aziende presenti a SAIE Bari 2025<\/h3>\n<p style=\"text-align: center\"><a class=\"btn btn-lg btn-primary my-1\" href=\"https:\/\/espositori.saiebari.it\/portale\/it\/espositori\" target=\"_blank\" rel=\"noopener\">Elenco Espositori<\/a><\/p>\n[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row equal_height=&#8221;yes&#8221; el_class=&#8221;my-1&#8243;][vc_column width=&#8221;2\/3&#8243; el_class=&#8221;px-lg-5&#8243;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column_inner][vc_column_text] Tecnologie e strumenti per il restauro e la conservazione [\/vc_column_text][vc_column_text]Assorestauro ha organizzato nell\u2019ambito di SAIE Bari 2025 la Piazza Cantiere del Restauro, uno spazio dedicato ad attivit\u00e0 pratiche, workshop applicativi e panel tecnici per un evento a 360\u00b0 sul mondo della riqualificazione. Un\u2019occasione di incontro tra aziende, professionisti, [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":16901,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/pages\/19474"}],"collection":[{"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/comments?post=19474"}],"version-history":[{"count":3,"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/pages\/19474\/revisions"}],"predecessor-version":[{"id":23707,"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/pages\/19474\/revisions\/23707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/media\/16901"}],"wp:attachment":[{"href":"https:\/\/www.saiebari.it\/it\/wp-json\/wp\/v2\/media?parent=19474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}